{"id":96019,"date":"2026-09-02T14:55:52","date_gmt":"2026-09-02T17:55:52","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/09\/02\/membros-do-cv-sao-condenados-a-110-anos-de-prisao-por-matar-rapaz-a-pauladas-e-jogar-corpo-em-rio\/"},"modified":"2026-09-02T14:55:52","modified_gmt":"2026-09-02T17:55:52","slug":"membros-do-cv-sao-condenados-a-110-anos-de-prisao-por-matar-rapaz-a-pauladas-e-jogar-corpo-em-rio","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/09\/02\/membros-do-cv-sao-condenados-a-110-anos-de-prisao-por-matar-rapaz-a-pauladas-e-jogar-corpo-em-rio\/","title":{"rendered":"Membros do CV s\u00e3o condenados a 110 anos de pris\u00e3o por matar rapaz a pauladas e jogar corpo em rio"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/09\/WhatsApp-Image-2026-09-02-at-12_33_13.jpeg\" alt=\"Membros do CV s&#xE3;o condenados a 110 anos de pris&#xE3;o por matar rapaz a pauladas e jogar corpo em rio\"><\/p>\n<p>O Tribunal do J&#xFA;ri de Sorriso condenou, nesta ter&#xE7;a-feira (1), Alison Ant&#xF4;nio Silva Vieira, Max Matos de Sousa, Eduardo Vieira da Concei&#xE7;&#xE3;o e Willian da Silva Soares pelo assassinato de Maur&#xED;cio dos Santos Silva de Ara&#xFA;jo, ocorrido em janeiro de 2024.&#xA0;<\/p>\n<p>Os quatro foram condenados por homic&#xED;dio triplamente qualificado, oculta&#xE7;&#xE3;o de cad&#xE1;ver e corrup&#xE7;&#xE3;o de menores. Alison, Max e Eduardo tamb&#xE9;m foram condenados por integrarem organiza&#xE7;&#xE3;o criminosa. As penas aplicadas aos quatro r&#xE9;us somam 110 anos de pris&#xE3;o.&#xA0;<\/p>\n<p>Segundo a investiga&#xE7;&#xE3;o, o crime ocorreu em contexto de atua&#xE7;&#xE3;o do Comando Vermelho (CV) e foi motivado pela suspeita de que Maur&#xED;cio pertencesse ao Primeiro Comando da Capital (PCC), fac&#xE7;&#xE3;o rival. A desconfian&#xE7;a surgiu a partir de uma tatuagem no peito da v&#xED;tima, interpretada pelos envolvidos como indicativo de liga&#xE7;&#xE3;o ao grupo advers&#xE1;rio.&#xA0;<\/p>\n<p>A partir dessa suspeita, Max, Willian e um adolescente conduziram Maur&#xED;cio &#xE0; for&#xE7;a para uma quitinete. No local, a v&#xED;tima foi dominada e amarrada, passando a ser interrogada e agredida. Eduardo chegou &#xE0; quitinete, tamb&#xE9;m interrogou Maur&#xED;cio sobre a suposta liga&#xE7;&#xE3;o com a fac&#xE7;&#xE3;o rival e ajudou nas agress&#xF5;es.&#xA0;<\/p>\n<p>Na sequ&#xEA;ncia, o grupo levou Maur&#xED;cio para um terreno baldio, onde Alison se juntou aos demais e realizou uma chamada de v&#xED;deo com outros integrantes da organiza&#xE7;&#xE3;o criminosa, enquanto a v&#xED;tima continuava sendo interrogada sobre sua suposta vincula&#xE7;&#xE3;o ao PCC. Ainda amarrado os faccionados bateram com peda&#xE7;o de madeira na cabe&#xE7;a de Maur&#xED;cio que veio a &#xF3;bito. O exame pericial apontou traumatismo craniano provocado por a&#xE7;&#xE3;o contundente como causa da morte.&#xA0;<\/p>\n<p>Ap&#xF3;s o homic&#xED;dio, o corpo foi transportado e lan&#xE7;ado no Rio Lira, em Sorriso, com a finalidade de ocult&#xE1;-lo. Na manh&#xE3; seguinte, o cad&#xE1;ver foi localizado preso a galhadas. Maur&#xED;cio estava amorda&#xE7;ado e com os p&#xE9;s amarrados.&#xA0;<\/p>\n<p>O Conselho de Senten&#xE7;a reconheceu que o homic&#xED;dio foi praticado por motivo torpe, com emprego de meio cruel e mediante recurso que dificultou a defesa da v&#xED;tima. O motivo torpe decorreu do contexto de disputa entre fac&#xE7;&#xF5;es criminosas e da suspeita de que Maur&#xED;cio pertencesse a um grupo rival. <\/p>\n<p>O meio cruel foi reconhecido em raz&#xE3;o da sequ&#xEA;ncia de submiss&#xE3;o, interrogat&#xF3;rios e agress&#xF5;es imposta &#xE0; v&#xED;tima antes da morte. J&#xE1; o recurso que dificultou a defesa decorreu das circunst&#xE2;ncias em que Maur&#xED;cio permaneceu amarrado, subjugado e em inferioridade diante do grupo.&#xA0;<\/p>\n<p>Os jurados tamb&#xE9;m reconheceram os crimes de oculta&#xE7;&#xE3;o de cad&#xE1;ver, pelo lan&#xE7;amento do corpo no Rio Lira ap&#xF3;s o homic&#xED;dio, e de corrup&#xE7;&#xE3;o de menores, em raz&#xE3;o da participa&#xE7;&#xE3;o de um adolescente na a&#xE7;&#xE3;o criminosa.&#xA0;<\/p>\n<p>Alison Ant&#xF4;nio Silva Vieira foi condenado a 36 anos de pris&#xE3;o pelos crimes de homic&#xED;dio triplamente qualificado, oculta&#xE7;&#xE3;o de cad&#xE1;ver, organiza&#xE7;&#xE3;o criminosa e corrup&#xE7;&#xE3;o de menores.&#xA0;<\/p>\n<p>Max Matos de Sousa e Eduardo Vieira da Concei&#xE7;&#xE3;o foram condenados pelos mesmos crimes, cada um &#xE0; pena de 25 anos e 10 meses de pris&#xE3;o.&#xA0;<\/p>\n<p>Willian da Silva Soares foi condenado a 22 anos e quatro meses de pris&#xE3;o por homic&#xED;dio triplamente qualificado, oculta&#xE7;&#xE3;o de cad&#xE1;ver e corrup&#xE7;&#xE3;o de menores.&#xA0;<\/p>\n<p>Ao comentar o resultado do julgamento, o promotor de Justi&#xE7;a Luiz Fernando Rossi Pipino destacou a import&#xE2;ncia do enfrentamento institucional &#xE0;s organiza&#xE7;&#xF5;es criminosas. &#x201C;N&#xE3;o vamos admitir que organiza&#xE7;&#xF5;es criminosas imponham suas pr&#xF3;prias leis, promovam julgamentos clandestinos e decidam quem pode viver ou morrer. O Estado n&#xE3;o pode recuar diante das fac&#xE7;&#xF5;es. O enfrentamento ao crime organizado ser&#xE1; firme, permanente e dentro da lei&#x201D;, declarou.<\/p>\n<p><strong>Fonte:<\/strong> Policial &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/integrantes-do-cv-sao-condenados-a-110-anos-por-matar-rapaz-a-pauladas\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal do J&#xFA;ri de Sorriso condenou, nesta ter&#xE7;a-feira (1), Alison Ant&#xF4;nio Silva Vieira, Max<\/p>\n","protected":false},"author":2,"featured_media":96020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/96019"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=96019"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/96019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/96020"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=96019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=96019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=96019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}