{"id":96013,"date":"2026-09-02T12:56:17","date_gmt":"2026-09-02T15:56:17","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/09\/02\/homem-e-preso-por-furto-de-energia-em-operacao-que-apura-morte-de-menor-que-soltava-pipa\/"},"modified":"2026-09-02T12:56:17","modified_gmt":"2026-09-02T15:56:17","slug":"homem-e-preso-por-furto-de-energia-em-operacao-que-apura-morte-de-menor-que-soltava-pipa","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/09\/02\/homem-e-preso-por-furto-de-energia-em-operacao-que-apura-morte-de-menor-que-soltava-pipa\/","title":{"rendered":"Homem \u00e9 preso por furto de energia em opera\u00e7\u00e3o que apura morte de menor que soltava pipa"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/09\/60bbe88c37c95f2f47a571c9101ada42.jpg\" alt=\"Homem &#xE9; preso por furto de energia em opera&#xE7;&#xE3;o que apura morte de menor que soltava pipa\"><\/p>\n<p>A Pol&#xED;cia Civil de Mato Grosso deflagrou, na ter&#xE7;a-feira (1), a segunda fase da <strong>Opera&#xE7;&#xE3;o Philippe Pinel<\/strong>, para cumprimento de ordens judiciais em continuidade &#xE0;s investiga&#xE7;&#xF5;es relacionadas ao homic&#xED;dio de um adolescente de 17 anos, ocorrido em julho deste ano no munic&#xED;pio.<\/p>\n<p>Na opera&#xE7;&#xE3;o, foram cumpridos quatro mandados de busca e apreens&#xE3;o expedidos pela 1&#xAA; Vara Criminal de Rondon&#xF3;polis, com base em investiga&#xE7;&#xF5;es conduzidas pela Delegacia Especializadas de Homic&#xED;dios e Prote&#xE7;&#xE3;o &#xE0; Pessoa (DHPP) do munic&#xED;pio. As ordens judiciais foram cumpridas em endere&#xE7;os localizados nos bairros Serra Dourada, Dom Os&#xF3;rio, Sumar&#xE9; e Vila Mineira.<\/p>\n<p>As medidas judiciais t&#xEA;m como objetivo subsidiar a investiga&#xE7;&#xE3;o e reunir novos elementos para o completo esclarecimento do crime. No decorrer da opera&#xE7;&#xE3;o, um homem de 32 anos foi preso em flagrante pelos crimes de furto de energia el&#xE9;trica, fraude e organiza&#xE7;&#xE3;o criminosa.<\/p>\n<p>A segunda fase &#xE9; resultado do avan&#xE7;o das investiga&#xE7;&#xF5;es da DHPP, que identificaram novos elementos sobre a din&#xE2;mica do homic&#xED;dio e o poss&#xED;vel envolvimento de outras pessoas no crime.<\/p>\n<p><strong>Primeira fase<\/strong><\/p>\n<p>A primeira fase da <strong>Opera&#xE7;&#xE3;o Philippe Pinel <\/strong>ocorreu em 18 de agosto, quando foram cumpridas tr&#xEA;s ordens judiciais: dois mandados de busca e apreens&#xE3;o e um de pris&#xE3;o. Durante a a&#xE7;&#xE3;o, uma quarta pessoa tamb&#xE9;m foi presa em flagrante.<\/p>\n<p><strong>Relembre o caso<\/strong><\/p>\n<p>O adolescente foi assassinado na noite de 14 de julho de 2026, no bairro Serra Dourada, em Rondon&#xF3;polis. As investiga&#xE7;&#xF5;es indicam que a v&#xED;tima estava soltando pipa na companhia de outros jovens quando foi atingida por disparos de arma de fogo.<\/p>\n<p>As investiga&#xE7;&#xF5;es permanecem em andamento e s&#xE3;o conduzidas pela Pol&#xED;cia Civil com o objetivo de esclarecer integralmente as circunst&#xE2;ncias do homic&#xED;dio, bem como identificar e responsabilizar eventuais outros envolvidos.<\/p>\n<p><strong>Nome da opera&#xE7;&#xE3;o<\/strong><\/p>\n<p>A <strong>Opera&#xE7;&#xE3;o Philippe Pinel <\/strong>recebeu esse nome em refer&#xEA;ncia ao m&#xE9;dico franc&#xEA;s Philippe Pinel, reconhecido por sua atua&#xE7;&#xE3;o no campo da psiquiatria e por defender uma abordagem mais humanizada no tratamento de pessoas com transtornos mentais, em contraposi&#xE7;&#xE3;o &#xE0;s pr&#xE1;ticas violentas adotadas &#xE0; &#xE9;poca.<\/p>\n<p><strong>Fonte:<\/strong> Policial &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/homem-e-preso-por-furto-de-energia-em-operacao-que-apura-morte-de-menor-que-soltava-pipa\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol&#xED;cia Civil de Mato Grosso deflagrou, na ter&#xE7;a-feira (1), a segunda fase da Opera&#xE7;&#xE3;o<\/p>\n","protected":false},"author":2,"featured_media":96014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/96013"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=96013"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/96013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/96014"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=96013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=96013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=96013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}