{"id":95913,"date":"2026-09-01T17:55:47","date_gmt":"2026-09-01T20:55:47","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/09\/01\/tre-regulamenta-propaganda-gratuita-e-formaliza-sistema-que-fiscaliza-cotas\/"},"modified":"2026-09-01T17:55:47","modified_gmt":"2026-09-01T20:55:47","slug":"tre-regulamenta-propaganda-gratuita-e-formaliza-sistema-que-fiscaliza-cotas","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/09\/01\/tre-regulamenta-propaganda-gratuita-e-formaliza-sistema-que-fiscaliza-cotas\/","title":{"rendered":"TRE regulamenta propaganda gratuita e formaliza sistema que fiscaliza cotas"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/09\/image-1140-c4c89e5ca70f1d02e147502f9fdfb217.jpeg\" alt=\"TRE regulamenta propaganda gratuita e formaliza sistema que fiscaliza cotas\"><\/p>\n<p>O Tribunal Regional Eleitoral de Mato Grosso (TRE-MT) publicou a Portaria n&#xBA; 1\/2026-JAP, expedida pela ju&#xED;za auxiliar da Presid&#xEA;ncia, Edna Ederli Coutinho, coordenadora do Hor&#xE1;rio Eleitoral Gratuito. O documento disciplina a operacionaliza&#xE7;&#xE3;o da propaganda eleitoral gratuita no r&#xE1;dio e na televis&#xE3;o para as Elei&#xE7;&#xF5;es 2026 no Estado. <\/p>\n<p>Entre as principais novidades est&#xE1; a formaliza&#xE7;&#xE3;o da implanta&#xE7;&#xE3;o do Sistema HEG-M&#xED;dias, ferramenta desenvolvida para garantir a transpar&#xEA;ncia e o cumprimento rigoroso das cotas afirmativas destinadas a candidaturas de mulheres, pessoas negras e ind&#xED;genas.&#xA0;<\/p>\n<p>A norma estabelece os procedimentos formais para partidos, federa&#xE7;&#xF5;es, coliga&#xE7;&#xF5;es e ve&#xED;culos de comunica&#xE7;&#xE3;o durante todo o per&#xED;odo eleitoral, abrangendo tanto o primeiro quanto o eventual segundo turno. Uma das diretrizes centrais da portaria &#xE9; o uso do M&#xF3;dulo Controle de Cotas do Sistema HEG-M&#xED;dias. <\/p>\n<p>Desenvolvida pelo Tribunal, a plataforma cruza dados do registro de candidaturas (CandidaturAS\/TSE) e do plano de m&#xED;dia oficial para aferir se o tempo proporcional de r&#xE1;dio e TV reservado por lei a mulheres, negros e ind&#xED;genas est&#xE1; sendo cumprido.&#xA0;<\/p>\n<p>A fiscaliza&#xE7;&#xE3;o das cotas ser&#xE1; aplicada &#xE0;s candidaturas de deputado federal e deputado estadual. O acompanhamento ocorrer&#xE1; por ciclos semanais e ao t&#xE9;rmino de toda a campanha, permitindo que as legendas identifiquem pend&#xEA;ncias e realizem as devidas compensa&#xE7;&#xF5;es nos programas subsequentes antes do t&#xE9;rmino do per&#xED;odo eleitoral. <\/p>\n<p>Para que o monitoramento seja efetivo, os partidos e federa&#xE7;&#xF5;es dever&#xE3;o cadastrar semanalmente no sistema as informa&#xE7;&#xF5;es complementares das pe&#xE7;as veiculadas, al&#xE9;m de manter atualiza&#xE7;&#xE3;o frequente quanto ao conte&#xFA;do.<\/p>\n<p><strong>Gera&#xE7;&#xE3;o e Especifica&#xE7;&#xF5;es<\/strong><\/p>\n<p>A portaria tamb&#xE9;m definiu as empresas respons&#xE1;veis por encabe&#xE7;ar a gera&#xE7;&#xE3;o do sinal da propaganda em rede no estado de Mato Grosso. Enquanto a gera&#xE7;&#xE3;o do sinal para r&#xE1;dio ficou com o Grupo Gazeta (Sociedade R&#xE1;dio Vila Real LTDA). A de televis&#xE3;o ficou com a TV Centro Am&#xE9;rica (Televis&#xE3;o Centro Am&#xE9;rica LTDA).<\/p>\n<p>As m&#xED;dias de r&#xE1;dio devem ser encaminhadas por e-mail no formato MP3 (taxa de bits superior a 128 kbps). J&#xE1; no caso da televis&#xE3;o, o material dever&#xE1; seguir o padr&#xE3;o HD (resolu&#xE7;&#xE3;o 1920x1080i, codec XDCAM HD422 a 50 Mbps em reposit&#xF3;rio MXF OP1a). O envio das m&#xED;dias de TV para a emissora geradora e afiliadas ser&#xE1; realizado exclusivamente via players ou plataformas digitais homologadas (Vati, Peach\/A+V Zarpa e Extreme Reach).<\/p>\n<p><strong>Prazos<\/strong>&#xA0;<\/p>\n<p>A Justi&#xE7;a Eleitoral refor&#xE7;ou a import&#xE2;ncia do cumprimento dos hor&#xE1;rios de entrega de materiais por parte das ag&#xEA;ncias e partidos pol&#xED;ticos:&#xA0;<\/p>\n<p>&#8211; Mapas de m&#xED;dia e inser&#xE7;&#xF5;es (r&#xE1;dio e TV): at&#xE9; as 14h30 do dia &#xFA;til imediatamente anterior &#xE0; exibi&#xE7;&#xE3;o.<\/p>\n<p>&#8211; Agrupamento de inser&#xE7;&#xF5;es (30s para 60s): at&#xE9; as 8h30 do 2&#xBA; dia &#xFA;til anterior &#xE0; veicula&#xE7;&#xE3;o.<\/p>\n<p>&#8211; Rede de R&#xE1;dio (blocos das 6h e 11h): at&#xE9; as 14h30 do dia &#xFA;til anterior.<\/p>\n<p>&#8211; Rede de TV (bloco das 12h): at&#xE9; as 16h do dia &#xFA;til anterior.<\/p>\n<p>&#8211; Rede de TV (bloco das 19h30): at&#xE9; as 12h do pr&#xF3;prio dia da veicula&#xE7;&#xE3;o.&#xA0;<\/p>\n<p>Para efeitos de contagem de prazos operacionais, os s&#xE1;bados n&#xE3;o ser&#xE3;o considerados dias &#xFA;teis. As emissoras ter&#xE3;o at&#xE9; 30 minutos ap&#xF3;s o recebimento para confirmar a integridade dos arquivos ou motivar formalmente qualquer recusa t&#xE9;cnica.<\/p>\n<p><strong>Fonte:<\/strong> Pol\u00edtica &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/tre-regulamenta-propaganda-gratuita-e-formaliza-sistema-que-fiscaliza-cotas\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Regional Eleitoral de Mato Grosso (TRE-MT) publicou a Portaria n&#xBA; 1\/2026-JAP, expedida pela<\/p>\n","protected":false},"author":2,"featured_media":95914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95913"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=95913"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/95914"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=95913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=95913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=95913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}