{"id":95905,"date":"2026-09-01T17:55:42","date_gmt":"2026-09-01T20:55:42","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/09\/01\/por-unanimidade-camara-aprova-parcelamento-de-divida-de-r-30-milhoes-da-prefeitura-de-cuiaba\/"},"modified":"2026-09-01T17:55:42","modified_gmt":"2026-09-01T20:55:42","slug":"por-unanimidade-camara-aprova-parcelamento-de-divida-de-r-30-milhoes-da-prefeitura-de-cuiaba","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/09\/01\/por-unanimidade-camara-aprova-parcelamento-de-divida-de-r-30-milhoes-da-prefeitura-de-cuiaba\/","title":{"rendered":"Por unanimidade, C\u00e2mara aprova parcelamento de d\u00edvida de R$ 30 milh\u00f5es da Prefeitura de Cuiab\u00e1"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/09\/b4e003fc-4638-46c0-88e6-5338b848b0bc.jpg\" alt=\"Por unanimidade, C&#xE2;mara aprova parcelamento de d&#xED;vida de R$ 30 milh&#xF5;es da Prefeitura de Cuiab&#xE1;\"><\/p>\n<p>Os vereadores de Cuiab&#xE1; aprovaram por unanimidade, na sess&#xE3;o desta ter&#xE7;a-feira (1), o projeto de lei do Executivo que autoriza o parcelamento especial de uma d&#xED;vida do Munic&#xED;pio com a Uni&#xE3;o. A medida permitir&#xE1; reduzir o valor das parcelas e dar&#xE1; maior f&#xF4;lego ao caixa da atual administra&#xE7;&#xE3;o, sem criar custo ou nova despesa para os cofres municipais.<\/p>\n<p>O saldo da d&#xED;vida considerado para a renegocia&#xE7;&#xE3;o &#xE9; de R$ 30,46 milh&#xF5;es. Atualmente, o Munic&#xED;pio possui previs&#xE3;o de pagamento em 42 parcelas de aproximadamente R$ 846,4 mil. Com a ades&#xE3;o ao programa federal, a d&#xED;vida poder&#xE1; ser quitada em at&#xE9; 360 parcelas, com atualiza&#xE7;&#xE3;o pelo IPCA e juros reais de 0% ao ano.<\/p>\n<p>Na modalidade escolhida pela Prefeitura, a administra&#xE7;&#xE3;o municipal tamb&#xE9;m dever&#xE1; aplicar anualmente 4% do saldo atualizado da d&#xED;vida em investimentos que atendam aos crit&#xE9;rios estabelecidos pela legisla&#xE7;&#xE3;o. Ainda assim, a estimativa &#xE9; de uma redu&#xE7;&#xE3;o bruta de aproximadamente R$ 9,14 milh&#xF5;es por ano nas despesas com o servi&#xE7;o da d&#xED;vida.<\/p>\n<p>Descontado o valor que dever&#xE1; ser destinado aos investimentos, o Munic&#xED;pio ter&#xE1; um espa&#xE7;o fiscal l&#xED;quido estimado em R$ 7,92 milh&#xF5;es por ano, equivalente a cerca de R$ 660 mil por m&#xEA;s. Na pr&#xE1;tica, o mecanismo reduz a press&#xE3;o sobre o caixa e permite que recursos antes comprometidos com o pagamento das parcelas sejam utilizados em outras &#xE1;reas e obriga&#xE7;&#xF5;es da administra&#xE7;&#xE3;o.<\/p>\n<p>A justificativa apresentada pelo Executivo destaca que a medida representa um &#x201C;expressivo al&#xED;vio no fluxo de caixa mensal&#x201D; e possibilita a &#x201C;elimina&#xE7;&#xE3;o da onerosidade da taxa de juros&#x201D; da d&#xED;vida. O texto tamb&#xE9;m aponta que a renegocia&#xE7;&#xE3;o contribui para ampliar a capacidade financeira do Munic&#xED;pio e reduzir riscos relacionados &#xE0; reten&#xE7;&#xE3;o de recursos do Fundo de Participa&#xE7;&#xE3;o dos Munic&#xED;pios (FPM).<\/p>\n<p>Outro ponto destacado na proposta &#xE9; que a opera&#xE7;&#xE3;o n&#xE3;o representa a cria&#xE7;&#xE3;o de uma nova obriga&#xE7;&#xE3;o financeira. Conforme a declara&#xE7;&#xE3;o de compatibilidade fiscal assinada pelo secret&#xE1;rio municipal de Economia, Marcelo Bussiki, e pelo controlador-geral do Munic&#xED;pio, Eder Galiciani, a d&#xED;vida j&#xE1; existe, est&#xE1; prevista no or&#xE7;amento e a reestrutura&#xE7;&#xE3;o apenas modifica suas condi&#xE7;&#xF5;es de pagamento.<\/p>\n<p>Os respons&#xE1;veis pela &#xE1;rea fiscal afirmam que a medida &#x201C;n&#xE3;o acarreta impacto or&#xE7;ament&#xE1;rio-financeiro negativo nos exerc&#xED;cios&#x201D;. Dessa forma, o parcelamento busca melhorar o fluxo financeiro sem gerar custo extra para o Munic&#xED;pio.<\/p>\n<p>A proposta tamb&#xE9;m estabelece que fica &#x201C;vedada a contrata&#xE7;&#xE3;o de novas opera&#xE7;&#xF5;es de cr&#xE9;dito para o pagamento das parcelas&#x201D;, impedindo que a renegocia&#xE7;&#xE3;o seja utilizada para criar novo endividamento com essa finalidade.<\/p>\n<p>A ades&#xE3;o est&#xE1; baseada na Emenda Constitucional n&#xBA; 136\/2025 e em regulamenta&#xE7;&#xF5;es federais que permitem o refinanciamento de d&#xE9;bitos municipais com condi&#xE7;&#xF5;es mais favor&#xE1;veis. A Prefeitura precisa formalizar a ades&#xE3;o junto &#xE0; Secretaria do Tesouro Nacional at&#xE9; 9 de setembro de 2026.<\/p>\n<p><strong>Fonte:<\/strong> Pol\u00edtica &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/por-unanimidade-camara-aprova-parcelamento-de-divida-de-r-30-milhoes-da-prefeitura\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os vereadores de Cuiab&#xE1; aprovaram por unanimidade, na sess&#xE3;o desta ter&#xE7;a-feira (1), o projeto de<\/p>\n","protected":false},"author":2,"featured_media":95906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95905"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=95905"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/95906"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=95905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=95905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=95905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}