{"id":90672,"date":"2026-07-15T13:55:41","date_gmt":"2026-07-15T16:55:41","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/07\/15\/saiba-quem-e-o-dono-de-posto-preso-durante-operacao-por-estupro-de-vulneravel-em-mt\/"},"modified":"2026-07-15T13:55:41","modified_gmt":"2026-07-15T16:55:41","slug":"saiba-quem-e-o-dono-de-posto-preso-durante-operacao-por-estupro-de-vulneravel-em-mt","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/07\/15\/saiba-quem-e-o-dono-de-posto-preso-durante-operacao-por-estupro-de-vulneravel-em-mt\/","title":{"rendered":"Saiba quem \u00e9 o dono de posto preso durante opera\u00e7\u00e3o por estupro de vulner\u00e1vel em MT"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/07\/a-a-59.jpg\" alt=\"Saiba quem &#xE9; o dono de posto preso durante opera&#xE7;&#xE3;o por estupro de vulner&#xE1;vel em MT\"><\/p>\n<p><strong><em>Conte&#xFA;do\/ODOC<\/em><\/strong> &#8211; O empres&#xE1;rio F&#xE1;bio Serafim de Oliveira, de 42 anos, dono de um posto de combust&#xED;veis &#xE0;s margens da BR-163, em Sorriso (398 km de Cuiab&#xE1;), foi preso na manh&#xE3; desta quarta-feira (15) durante a <strong>Opera&#xE7;&#xE3;o Puer Defensus<\/strong>.<\/p>\n<p>Ele &#xE9; investigado por estupro de vulner&#xE1;vel, al&#xE9;m de divulga&#xE7;&#xE3;o e armazenamento de material de explora&#xE7;&#xE3;o sexual infantojuvenil.<\/p>\n<p>A a&#xE7;&#xE3;o foi deflagrada pela Pol&#xED;cia Civil, que cumpriu um mandado de pris&#xE3;o preventiva contra o empres&#xE1;rio e dois mandados de busca e apreens&#xE3;o: um na resid&#xEA;ncia de F&#xE1;bio e outro na casa da esposa dele, de 45 anos, tamb&#xE9;m investigada por suposta participa&#xE7;&#xE3;o nos crimes.<\/p>\n<p>A mulher n&#xE3;o foi presa, mas foi submetida a medidas cautelares determinadas pela Justi&#xE7;a, entre elas a quebra do sigilo telef&#xF4;nico e a apreens&#xE3;o de aparelhos eletr&#xF4;nicos.<\/p>\n<p>Durante as buscas, os policiais apreenderam armas de fogo, muni&#xE7;&#xF5;es, celulares, computadores, m&#xED;dias de armazenamento, o chip do sistema de c&#xE2;meras de seguran&#xE7;a, fitas VHS e outros materiais, que ser&#xE3;o periciados para auxiliar no andamento das investiga&#xE7;&#xF5;es.<\/p>\n<p>Segundo a Pol&#xED;cia Civil, o caso teve in&#xED;cio ap&#xF3;s a pris&#xE3;o de uma mulher suspeita de aliciar menores de idade e fornecer material audiovisual com cenas de explora&#xE7;&#xE3;o sexual infantil.<\/p>\n<p>A an&#xE1;lise do celular da investigada e o depoimento prestado por ela permitiram identificar o casal alvo da opera&#xE7;&#xE3;o.<\/p>\n<p>Conforme a investiga&#xE7;&#xE3;o, foram encontrados ind&#xED;cios da exist&#xEA;ncia de v&#xED;deos e fotografias envolvendo v&#xED;timas menores de idade e o empres&#xE1;rio, o que embasou os pedidos de pris&#xE3;o preventiva e de busca e apreens&#xE3;o autorizados pela Justi&#xE7;a.<\/p>\n<p>A <strong>Opera&#xE7;&#xE3;o Puer Defensus<\/strong> mobilizou duas equipes da Delegacia de Sorriso, com oito policiais civis e duas viaturas, al&#xE9;m do apoio da Secretaria Municipal de Seguran&#xE7;a P&#xFA;blica, que utilizou um drone para monitorar o per&#xED;metro durante o cumprimento das ordens judiciais.<\/p>\n<p>As investiga&#xE7;&#xF5;es seguem em sigilo devido &#xE0; natureza dos crimes e por envolverem v&#xED;timas menores de idade. A Pol&#xED;cia Civil informou que continua apurando o caso para identificar poss&#xED;veis coautores e responsabilizar todos os envolvidos.<\/p>\n<p><strong>Fonte:<\/strong> Policial &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/saiba-quem-e-o-dono-de-posto-preso-durante-operacao-por-estupro-de-vulneravel-em-mt\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conte&#xFA;do\/ODOC &#8211; O empres&#xE1;rio F&#xE1;bio Serafim de Oliveira, de 42 anos, dono de um posto<\/p>\n","protected":false},"author":2,"featured_media":90673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/90672"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=90672"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/90672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/90673"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=90672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=90672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=90672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}