{"id":90670,"date":"2026-07-15T11:55:57","date_gmt":"2026-07-15T14:55:57","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/07\/15\/vereadores-de-varzea-grande-pedem-sessao-extraordinaria-para-votar-orcamento\/"},"modified":"2026-07-15T11:55:57","modified_gmt":"2026-07-15T14:55:57","slug":"vereadores-de-varzea-grande-pedem-sessao-extraordinaria-para-votar-orcamento","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/07\/15\/vereadores-de-varzea-grande-pedem-sessao-extraordinaria-para-votar-orcamento\/","title":{"rendered":"Vereadores de V\u00e1rzea Grande pedem sess\u00e3o extraordin\u00e1ria para votar or\u00e7amento"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/07\/503e12e745d166813533c006a7ed799a-rdnews-com-br.jpg\" alt=\"Vereadores de V&#xE1;rzea Grande pedem sess&#xE3;o extraordin&#xE1;ria para votar or&#xE7;amento\"><\/p>\n<p>A C&#xE2;mara Municipal de V&#xE1;rzea Grande recebeu nesta ter&#xE7;a-feira (14) um requerimento protocolado por 14 vereadores, solicitando uma sess&#xE3;o extraordin&#xE1;ria para vota&#xE7;&#xE3;o&#xA0;do projeto de lei que altera de 5% para 20% o limite para remanejamento or&#xE7;ament&#xE1;rio e abertura de cr&#xE9;ditos adicionais do munic&#xED;pio.&#xA0;&#xA0;A Prefeitura informou que j&#xE1; havia utilizado 4,99% dos 5% de remanejamento, dispon&#xED;veis no or&#xE7;amento<\/p>\n<p>Conforme artigo 138, do Regimento Interno da C&#xE2;mara, a convoca&#xE7;&#xE3;o pode ser feita durante o recesso pelo prefeito, ou por maioria absoluta dos vereadores, ou pela comiss&#xE3;o de representa&#xE7;&#xE3;o legislativa, mediante oficio ao seu presidente, para se reunir no m&#xED;nimo dentro de 24 horas.&#xA0;Agora, a decis&#xE3;o sobre a data de convoca&#xE7;&#xE3;o da sess&#xE3;o cabe ao presidente da C&#xE2;mara Municipal, vereador Wanderley Cerqueira (MDB).&#xA0;<\/p>\n<p>Assinaram o requerimento os vereadores Adilsinho (Republicanos), Charles da Educa&#xE7;&#xE3;o (Republicanos), Bruno Rios (PL), J&#xE2;nio Calistro (Uni&#xE3;o Brasil), Carlinhos Figueiredo (Republicanos), Caio Cordeiro (Novo), Cleyton Nassarden (MDB), Sargento Galibert (PSB), Enfermeiro Emerson (PP), Jero Neto (MDB), Lucas Chap&#xE9;u do Sol (PL), Joaquim Antunes (PSDB), Raul Curvo (Republicanos) e Rosy Prado (Uni&#xE3;o Brasil).<\/p>\n<p>De acordo com a Prefeitura de V&#xE1;rzea Grande, a aprova&#xE7;&#xE3;o da proposta &#xE9; necess&#xE1;ria para adequar o or&#xE7;amento e viabilizar a aplica&#xE7;&#xE3;o de emendas parlamentares destinadas &#xE0; Secretaria Municipal de Sa&#xFA;de, no valor de R$ 56,6 milh&#xF5;es. O munic&#xED;pio informa que grande parte desses recursos j&#xE1; est&#xE1; dispon&#xED;vel nas contas da Prefeitura, sendo necess&#xE1;ria apenas a autoriza&#xE7;&#xE3;o legal para sua execu&#xE7;&#xE3;o.<\/p>\n<p>A administra&#xE7;&#xE3;o municipal tamb&#xE9;m destaca a necessidade de suplementa&#xE7;&#xE3;o or&#xE7;ament&#xE1;ria de R$ 32 milh&#xF5;es para assegurar o equil&#xED;brio atuarial do Instituto de Seguridade Social dos Servidores P&#xFA;blicos de V&#xE1;rzea Grande (Previvag). Segundo a justificativa, o aporte contribuir&#xE1; para manter a regularidade fiscal do munic&#xED;pio, garantir o equil&#xED;brio financeiro e atuarial do Regime Pr&#xF3;prio de Previd&#xEA;ncia Social (RPPS) e assegurar a continuidade dos direitos previdenci&#xE1;rios dos servidores efetivos.<\/p>\n<p>Al&#xE9;m disso, a Prefeitura encaminhou &#xE0; C&#xE2;mara outros projetos que dependem da amplia&#xE7;&#xE3;o do limite para abertura de cr&#xE9;ditos adicionais, entre eles: R$ 5 milh&#xF5;es para a Secretaria Municipal de Meio Ambiente e Desenvolvimento Rural; R$ 3,3 milh&#xF5;es para a Secretaria Municipal de Sa&#xFA;de; R$ 23 milh&#xF5;es para a Secretaria Municipal de Servi&#xE7;os P&#xFA;blicos e Mobilidade Urbana; R$ 7,7 milh&#xF5;es para a Secretaria Municipal de Sa&#xFA;de.<\/p>\n<p>O l&#xED;der da prefeita na C&#xE2;mara, vereador Bruno Rios, afirmou que conforme o regimento, o presidente &#xE9; obrigado a convocar a sess&#xE3;o. &quot;Infelizmente, a prefeita teve uma margem de remanejamento muito pequena aprovada pela C&#xE2;mara. Sem essa aprova&#xE7;&#xE3;o, ficam prejudicadas a&#xE7;&#xF5;es governamentais, o recebimento de emendas parlamentares e a adequada presta&#xE7;&#xE3;o de servi&#xE7;os p&#xFA;blicos&quot;, afirmou.<\/p>\n<p><strong>Fonte:<\/strong> Pol\u00edtica &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/vereadores-de-varzea-grande-pedem-sessao-extraordinaria-para-votar-orcamento\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C&#xE2;mara Municipal de V&#xE1;rzea Grande recebeu nesta ter&#xE7;a-feira (14) um requerimento protocolado por 14<\/p>\n","protected":false},"author":2,"featured_media":90671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/90670"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=90670"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/90670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/90671"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=90670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=90670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=90670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}