{"id":90640,"date":"2026-07-15T09:55:44","date_gmt":"2026-07-15T12:55:44","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/07\/15\/pf-investiga-grupo-economico-por-fraudar-credito-consignado-e-lesar-servidores-publicos-de-mt\/"},"modified":"2026-07-15T09:55:44","modified_gmt":"2026-07-15T12:55:44","slug":"pf-investiga-grupo-economico-por-fraudar-credito-consignado-e-lesar-servidores-publicos-de-mt","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/07\/15\/pf-investiga-grupo-economico-por-fraudar-credito-consignado-e-lesar-servidores-publicos-de-mt\/","title":{"rendered":"PF investiga grupo econ\u00f4mico por fraudar cr\u00e9dito consignado e lesar servidores p\u00fablicos de MT"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/07\/images-11.jpg\" alt=\"PF investiga grupo econ&#xF4;mico por fraudar cr&#xE9;dito consignado e lesar servidores p&#xFA;blicos de MT\"><\/p>\n<p>A Pol&#xED;cia Federal deflagrou, nesta quarta-feira (15), a <strong>Opera&#xE7;&#xE3;o Fugazi<\/strong>, com o objetivo de aprofundar investiga&#xE7;&#xE3;o que apura a atua&#xE7;&#xE3;o de um grupo econ&#xF4;mico suspeito de utilizar opera&#xE7;&#xF5;es de cr&#xE9;dito consignado e cart&#xE3;o de cr&#xE9;dito consignado para praticar, em tese, fraudes em preju&#xED;zo de servidores p&#xFA;blicos, de aposentados e de pensionistas.<\/p>\n<p>Policiais federais cumprem 13 mandados de busca e apreens&#xE3;o nos estados de S&#xE3;o Paulo e do Rio Grande do Sul, expedidos pela Justi&#xE7;a Federal em Mato Grosso. Al&#xE9;m dos mandados de busca e apreens&#xE3;o, a Justi&#xE7;a determinou o sequestro de bens m&#xF3;veis e im&#xF3;veis e o bloqueio de valores e ativos financeiros dos investigados.<\/p>\n<p>A investiga&#xE7;&#xE3;o apura ind&#xED;cios de que empresas integrantes do grupo investigado teriam estruturado opera&#xE7;&#xF5;es financeiras apresentadas aos consumidores como cart&#xE3;o de cr&#xE9;dito consignado, mas que, na pr&#xE1;tica, funcionariam como empr&#xE9;stimos consignados, com juros elevados, mediante mecanismos que dificultariam a quita&#xE7;&#xE3;o da d&#xED;vida e poderiam ocasionar aumento do saldo devedor.<\/p>\n<p>Tamb&#xE9;m s&#xE3;o apurados poss&#xED;veis crimes contra o Sistema Financeiro Nacional, al&#xE9;m de ind&#xED;cios de lavagem de dinheiro, sem preju&#xED;zo de outros delitos que venham a ser identificados ao longo das investiga&#xE7;&#xF5;es.<\/p>\n<p>As medidas cautelares t&#xEA;m por finalidade reunir novos elementos probat&#xF3;rios, identificar o fluxo financeiro dos recursos e esclarecer a participa&#xE7;&#xE3;o dos investigados.<\/p>\n<p><strong>Fonte:<\/strong> Cidades &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/pf-investiga-grupo-economico-por-fraudar-credito-consignado-e-lesar-servidores-publicos-de-mt\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol&#xED;cia Federal deflagrou, nesta quarta-feira (15), a Opera&#xE7;&#xE3;o Fugazi, com o objetivo de aprofundar<\/p>\n","protected":false},"author":2,"featured_media":90641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/90640"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=90640"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/90640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/90641"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=90640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=90640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=90640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}