{"id":85279,"date":"2026-05-13T17:56:07","date_gmt":"2026-05-13T20:56:07","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/05\/13\/estado-realiza-obras-para-recuperar-asfalto-da-avenida-jurumirim-em-cuiaba\/"},"modified":"2026-05-13T17:56:07","modified_gmt":"2026-05-13T20:56:07","slug":"estado-realiza-obras-para-recuperar-asfalto-da-avenida-jurumirim-em-cuiaba","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/05\/13\/estado-realiza-obras-para-recuperar-asfalto-da-avenida-jurumirim-em-cuiaba\/","title":{"rendered":"Estado realiza obras para recuperar asfalto da Avenida Jurumirim em Cuiab\u00e1"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/05\/Jurumirim.jpg\" alt=\"Estado realiza obras para recuperar asfalto da Avenida Jurumirim em Cuiab&#xE1;\"><\/p>\n<p>O Governo de Mato Grosso recupera o asfalto da Avenida Jurumirim, em Cuiab&#xE1;. As obras j&#xE1; est&#xE3;o em andamento e recebem um investimento de R$ 3,7 milh&#xF5;es por parte da Secretaria de Estado de Infraestrutura e Log&#xED;stica (Sinfra).<\/p>\n<p>O trecho que est&#xE1; em obra tem 3,27 quil&#xF4;metros de extens&#xE3;o e vai da Avenida Miguel Sutil at&#xE9; a rotat&#xF3;ria com a Avenida Juliano Costa Marques, pr&#xF3;ximo &#xE0; Escola Estadual Militar Tiradentes, na regi&#xE3;o do bairro Carumb&#xE9;.<\/p>\n<p>O trabalho compreende a fresagem, ou seja, a retirada da camada atual de asfalto e a execu&#xE7;&#xE3;o de uma nova capa de pavimento, do tipo Concreto Betuminoso Usinado a Quente (CBUQ). Ap&#xF3;s a conclus&#xE3;o da pista de asfalto, ser&#xE1; realizada a sinaliza&#xE7;&#xE3;o.<\/p>\n<p>Atualmente, as obras est&#xE3;o sendo executadas nas proximidades do Posto de Sa&#xFA;de do Bela Vista. Com a raspagem do asfalto, a Sinfra orienta os motoristas a redobrarem a aten&#xE7;&#xE3;o para evitar acidentes.<\/p>\n<p>As obras devem continuar at&#xE9; o m&#xEA;s de agosto. O objetivo &#xE9; melhorar a qualidade do asfalto da avenida, que apresentava muito desgaste e ondula&#xE7;&#xF5;es. A Avenida Jurumirim, ou Gon&#xE7;alo Antunes de Barros, &#xE9; uma importante liga&#xE7;&#xE3;o entre a regi&#xE3;o do Grande CPA e o centro da capital.<\/p>\n<p><strong>Fonte:<\/strong> Cidades &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/estado-realiza-obras-para-recuperar-asfalto-da-avenida-jurumirim-em-cuiaba\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo de Mato Grosso recupera o asfalto da Avenida Jurumirim, em Cuiab&#xE1;. As obras<\/p>\n","protected":false},"author":2,"featured_media":85280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/85279"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=85279"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/85279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/85280"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=85279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=85279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=85279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}