{"id":85241,"date":"2026-05-13T11:56:12","date_gmt":"2026-05-13T14:56:12","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/05\/13\/pivetta-cobra-construtoras-que-firmam-pacto-para-concluir-brt-de-vg-ao-comando-da-pm-ate-junho\/"},"modified":"2026-05-13T11:56:12","modified_gmt":"2026-05-13T14:56:12","slug":"pivetta-cobra-construtoras-que-firmam-pacto-para-concluir-brt-de-vg-ao-comando-da-pm-ate-junho","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/05\/13\/pivetta-cobra-construtoras-que-firmam-pacto-para-concluir-brt-de-vg-ao-comando-da-pm-ate-junho\/","title":{"rendered":"Pivetta cobra construtoras que firmam pacto para concluir BRT de VG ao Comando da PM at\u00e9 junho"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/05\/64b2bf99-f9ac-482d-83ca-95c08aabd021.jpg\" alt=\"Pivetta cobra construtoras que firmam pacto para concluir BRT de VG ao Comando da PM at&#xE9; junho\"><\/p>\n<p>O governador Otaviano Pivetta cobrou as construtoras respons&#xE1;veis pelas obras do Sistema BRT entre Cuiab&#xE1; e V&#xE1;rzea Grande. Em resposta, as empresas firmaram, nesta quarta-feira (13), um pacto para a conclus&#xE3;o da faixa de 14 quil&#xF4;metros, entre o Aeroporto Marechal Rondon, em V&#xE1;rzea Grande, e o Comando Geral da Pol&#xED;cia Militar, em Cuiab&#xE1;, at&#xE9; o fim de junho.<\/p>\n<p>&#x201C;As empresas assumiram hoje o compromisso de entregar, at&#xE9; o fim de junho, toda essa faixa pronta, sinalizada e liberada. Sabemos o quanto essa obra trouxe transtornos para a popula&#xE7;&#xE3;o de Cuiab&#xE1; e V&#xE1;rzea Grande, mas agora estamos entrando em uma fase definitiva de conclus&#xE3;o. Para isso, uma equipe de trabalho vai atuar na fiscaliza&#xE7;&#xE3;o para garantir que esse cronograma seja cumprido. O povo cuiabano pode ter certeza de que vamos entregar essa faixa funcionando e trazendo mais mobilidade para toda a regi&#xE3;o metropolitana&#x201D;, disse.<\/p>\n<figure class=\"kg-card kg-image-card\"><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/05\/4d0811a1-9f81-44f0-b2be-0e5333a637da.jpg\" class=\"kg-image\" alt=\"Pivetta cobra construtoras que firmam pacto para concluir BRT de VG ao Comando da PM at&#xE9; junho\" loading=\"lazy\" width=\"1024\" height=\"682\"><\/figure>\n<p>O comerciante Valter relatou os impactos enfrentados por quem trabalha e circula diariamente pela regi&#xE3;o da Prainha e afirmou acompanhar a situa&#xE7;&#xE3;o h&#xE1; mais de uma d&#xE9;cada.<\/p>\n<p>&#x201C;Estou assistindo isso desde 2011, 2012. Conhe&#xE7;o o trabalho do senhor desde Lucas do Rio Verde e vejo que o senhor est&#xE1; acompanhando de perto. Isso faz a gente n&#xE3;o se sentir abandonado&#x201D;, afirmou.<\/p>\n<figure class=\"kg-card kg-image-card\"><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/05\/fd975bc1-2fd7-4abb-82fb-d00a5504a470.jpg\" class=\"kg-image\" alt=\"Pivetta cobra construtoras que firmam pacto para concluir BRT de VG ao Comando da PM at&#xE9; junho\" loading=\"lazy\" width=\"1024\" height=\"682\"><\/figure>\n<p>O governador destacou ainda que, ap&#xF3;s a conclus&#xE3;o deste primeiro trecho, o Estado dar&#xE1; sequ&#xEA;ncia aos demais ramais do sistema. &#x201C;Depois dessa etapa pronta e funcionando, vamos avan&#xE7;ar para os outros ramais que ir&#xE3;o interligar o transporte coletivo de Cuiab&#xE1; e V&#xE1;rzea Grande&#x201D;, completou.<\/p>\n<p><strong>Sobre o BRT<\/strong><\/p>\n<p>O Sistema BRT (Bus Rapid Transit) est&#xE1; em implanta&#xE7;&#xE3;o em Cuiab&#xE1; e V&#xE1;rzea Grande para oferecer um transporte coletivo mais r&#xE1;pido e eficiente &#xE0; popula&#xE7;&#xE3;o. O projeto prev&#xEA; corredores exclusivos para &#xF4;nibus de alta capacidade, esta&#xE7;&#xF5;es modernas, integra&#xE7;&#xE3;o com outros modais e melhorias urbanas ao longo do trajeto.<\/p>\n<p>O primeiro corredor liga o Terminal de V&#xE1;rzea Grande, pr&#xF3;ximo ao Aeroporto Marechal Rondon, at&#xE9; o Terminal do CPA, em Cuiab&#xE1;. J&#xE1; o segundo ramal far&#xE1; a liga&#xE7;&#xE3;o entre a regi&#xE3;o do Coxip&#xF3; e o centro da Capital, pela Avenida Fernando Corr&#xEA;a da Costa.<\/p>\n<p>Al&#xE9;m dos corredores exclusivos, o projeto tamb&#xE9;m prev&#xEA; requalifica&#xE7;&#xE3;o urbana, novas cal&#xE7;adas, drenagem, paisagismo e implanta&#xE7;&#xE3;o do Parque Linear na Avenida do CPA.<\/p>\n<p><strong>Fonte:<\/strong> Pol\u00edtica &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/pivetta-cobra-construtoras-que-firmam-pacto-para-concluir-brt-de-vg-ao-comando-da-pm-ate-junho\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Otaviano Pivetta cobrou as construtoras respons&#xE1;veis pelas obras do Sistema BRT entre Cuiab&#xE1;<\/p>\n","protected":false},"author":2,"featured_media":85242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/85241"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=85241"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/85241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/85242"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=85241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=85241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=85241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}