{"id":81122,"date":"2026-03-16T19:55:41","date_gmt":"2026-03-16T22:55:41","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/03\/16\/homem-morre-15-dias-apos-acidente-entre-moto-e-caminhao-que-matou-jovem\/"},"modified":"2026-03-16T19:55:41","modified_gmt":"2026-03-16T22:55:41","slug":"homem-morre-15-dias-apos-acidente-entre-moto-e-caminhao-que-matou-jovem","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2026\/03\/16\/homem-morre-15-dias-apos-acidente-entre-moto-e-caminhao-que-matou-jovem\/","title":{"rendered":"Homem morre 15 dias ap\u00f3s acidente entre moto e caminh\u00e3o que matou jovem"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/odocumento.com.br\/content\/images\/2026\/03\/b5785a3d-9849-439c-bf6d-96d82b637f66.jpg\" alt=\"Homem morre 15 dias ap&#xF3;s acidente entre moto e caminh&#xE3;o que matou jovem\"><\/p>\n<p><strong><em>Conte&#xFA;do\/ODOC<\/em><\/strong> &#8211; Um homem de 26 anos morreu nesta segunda-feira (16) em decorr&#xEA;ncia de um acidente envolvendo uma motocicleta e um caminh&#xE3;o bitrem registrado no in&#xED;cio do m&#xEA;s em Quer&#xEA;ncia (755 km de Cuiab&#xE1;). A colis&#xE3;o j&#xE1; havia causado a morte de uma jovem de 22 anos no dia do ocorrido.<\/p>\n<p>A v&#xED;tima que morreu ap&#xF3;s dias internada foi identificada como Edson Guedes Simpl&#xED;cio de Sousa. Ele estava hospitalizado desde o acidente, mas n&#xE3;o resistiu aos ferimentos.<\/p>\n<p>A colis&#xE3;o aconteceu no dia 1&#xBA; de mar&#xE7;o, por volta das 19h25, na Estrada R-20, nas proximidades da esquina com a Avenida Francisco Fridolino Scheneider. Segundo informa&#xE7;&#xF5;es da Pol&#xED;cia Civil, a motocicleta Honda CG 125 Fan KS estava parada no local quando foi atingida por um caminh&#xE3;o bitrem.<\/p>\n<p>De acordo com a investiga&#xE7;&#xE3;o, o ve&#xED;culo de carga seguia pela Estrada R-20 em dire&#xE7;&#xE3;o ao cemit&#xE9;rio da cidade e, ao realizar uma convers&#xE3;o &#xE0; direita, acabou colidindo com a motocicleta.<\/p>\n<p>No ve&#xED;culo estavam tr&#xEA;s ocupantes: Edson, a jovem Carliane Estev&#xE3;o de Sousa, de 22 anos, e uma crian&#xE7;a de 2 anos. Carliane morreu ainda no local em decorr&#xEA;ncia dos ferimentos.<\/p>\n<p>Edson foi socorrido e encaminhado para atendimento m&#xE9;dico, onde permaneceu internado desde ent&#xE3;o. No entanto, ap&#xF3;s cerca de duas semanas de tratamento, ele n&#xE3;o resistiu &#xE0;s les&#xF5;es.<\/p>\n<p>Ap&#xF3;s o acidente, o motorista do caminh&#xE3;o deixou o local sem prestar socorro &#xE0;s v&#xED;timas. Conforme a Pol&#xED;cia Civil, ele foi localizado posteriormente e autuado em flagrante pelo crime de homic&#xED;dio culposo na dire&#xE7;&#xE3;o de ve&#xED;culo automotor, previsto no artigo 302 do C&#xF3;digo de Tr&#xE2;nsito Brasileiro.<\/p>\n<p>O caminh&#xE3;o envolvido na ocorr&#xEA;ncia foi apreendido para os procedimentos legais, e o caso segue sendo investigado pela Pol&#xED;cia Civil.<\/p>\n<p><strong>Fonte:<\/strong> Policial &#8211; O DOCUMENTO | Confira as principais not\u00edcias de Cuiab\u00e1, Mato Grosso e regi\u00e3o (https:\/\/odocumento.com.br\/homem-morre-15-dias-apos-acidente-entre-moto-e-caminhao-que-matou-jovem-em-mt\/)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conte&#xFA;do\/ODOC &#8211; Um homem de 26 anos morreu nesta segunda-feira (16) em decorr&#xEA;ncia de um<\/p>\n","protected":false},"author":2,"featured_media":81123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/81122"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=81122"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/81122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/81123"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=81122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=81122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=81122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}