{"id":40465,"date":"2024-12-27T18:43:44","date_gmt":"2024-12-27T21:43:44","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/27\/ex-mulher-de-ney-latorraca-ines-galvao-se-emociona-em-velorio\/"},"modified":"2024-12-27T18:43:44","modified_gmt":"2024-12-27T21:43:44","slug":"ex-mulher-de-ney-latorraca-ines-galvao-se-emociona-em-velorio","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/27\/ex-mulher-de-ney-latorraca-ines-galvao-se-emociona-em-velorio\/","title":{"rendered":"Ex-mulher de Ney Latorraca, In\u00eas Galv\u00e3o se emociona em vel\u00f3rio"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; In\u00eas Galv\u00e3o, ex-mulher de Ney Latorraca, se emocionou durante o vel\u00f3rio do ator que aconteceu no Theatro Municipal do Rio de Janeiro<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A atriz falou sobre o a import\u00e2ncia do artista, com quem foi casada por quase cinco anos -entre 1983 e 1987. &#8220;Eu estava dentro do t\u00e1xi pensando&#8230; Eu n\u00e3o estava preparada para isso, nunca imaginei isso na minha vida, que eu viria no vel\u00f3rio do Ney! Na minha cabe\u00e7a, o Ney era imortal. Eu nunca pensei em um dia perder o Ney&#8221;, disse ao gshow.<\/p>\n<p>&#8220;O Ney estava sempre na minha vida em um canto especial, em um lugar especial da minha vida sempre. Eu n\u00e3o sei nem o que dizer, porque eu n\u00e3o sabia que ele estava doente&#8221;, disse In\u00eas Galv\u00e3o ao gshow.<\/p>\n<p>Nos \u00faltimos tempos, ela revelou n\u00e3o conseguir falar com ele por ter se isolado. &#8220;E eu achava que ele estava brigado comigo. Eu mandava &#8216;Whats App&#8217; e ele n\u00e3o respondia, eu ligava e ele n\u00e3o atendia. (&#8230;) Agora, estou descobrindo que n\u00e3o era isso. Ele n\u00e3o me contou que tinha sido diagnosticado (com c\u00e2ncer), talvez porque quisesse me preservar pelas hist\u00f3rias que eu j\u00e1 passei&#8230;&#8221;<\/p>\n<p>In\u00eas contou que descobriu que Ney tinha falecido ap\u00f3s ver um post de Miguel Falabella se despedindo do amigo. &#8220;Fui descobrindo&#8230; E passei um dia muito ruim ontem! (&#8230;) Tinha que vir dar um beijinho nele de despedida e agradecer tudo que ele foi na minha vida. Ele foi muito importante na minha vida como mulher, como pessoa e como atriz. Aprendi muito. Se sou alguma coisa como atriz, eu devo muito ao Ney&#8221;.<\/p>\n<p><span class=\"news_bold\">HIST\u00d3RICO DE SA\u00daDE<\/span><\/p>\n<p>A causa da morte foi uma sepse pulmonar ap\u00f3s o agravamento do c\u00e2ncer de pr\u00f3stata, com o qual foi diagnosticado em 2019.<\/p>\n<p>Ao receber o primeiro diagn\u00f3stico, Ney passou por uma cirurgia de remo\u00e7\u00e3o da pr\u00f3stata. A doen\u00e7a voltou em agosto deste ano, j\u00e1 com met\u00e1stase. Houve o tratamento inicial, por\u00e9m sem sucesso.<\/p>\n<p><span class=\"news_bold\">CARREIRA<\/span><\/p>\n<p>Antonio Ney Latorraca nasceu em Santos, S\u00e3o Paulo, no dia 25 de julho de 1944. Era filho de artistas, Alfredo, cantor e crooner de boates, e Tomaza, corista.<\/p>\n<p>Com apenas 6 anos, fez participa\u00e7\u00f5es na R\u00e1dio Record. Aos 19, passou em seu primeiro teste e fez &#8220;Pluft, o Fantasminha&#8221;, de Maria Clara Machado.<\/p>\n<p>Durante a d\u00e9cada de 1970, atuou em v\u00e1rios espet\u00e1culos, entre eles: &#8220;Hair&#8221; (1970), &#8220;Jesus Cristo Superstar&#8221; (1972), &#8220;Bodas de Sangue&#8221; (1973) e &#8220;A Mandr\u00e1gora&#8221; (1975).<\/p>\n<p>Paralelo \u00e0 carreira de ator, trabalhou em loja de roupa feminina, foi vendedor de pedras semipreciosas e funcion\u00e1rio de um banco.<\/p>\n<p>Ney Latorraca passou pela TV Tupi, TV Cultura, depois pela TV Record, onde trabalhou por cinco anos.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2243442\/20-familiares-e-amigos-se-despedem-de-ney-latorraca\" target=\"_blank\" rel=\"noopener\">Familiares e amigos se despedem de Ney Latorraca<\/a><\/p>\n<p>Fonte: noticiasaominuto.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; In\u00eas Galv\u00e3o, ex-mulher de Ney Latorraca, se emocionou durante o<\/p>\n","protected":false},"author":0,"featured_media":40466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40465"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40465"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/40466"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}