{"id":40449,"date":"2024-12-27T16:43:08","date_gmt":"2024-12-27T19:43:08","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/27\/vini-jr-e-unico-brasileiro-na-selecao-de-2024-da-federacao-de-historia-e-estatistica\/"},"modified":"2024-12-27T16:43:08","modified_gmt":"2024-12-27T19:43:08","slug":"vini-jr-e-unico-brasileiro-na-selecao-de-2024-da-federacao-de-historia-e-estatistica","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/27\/vini-jr-e-unico-brasileiro-na-selecao-de-2024-da-federacao-de-historia-e-estatistica\/","title":{"rendered":"Vini Jr. \u00e9 \u00fanico brasileiro na sele\u00e7\u00e3o de 2024 da federa\u00e7\u00e3o de hist\u00f3ria e estat\u00edstica"},"content":{"rendered":"<p>Vencedor do pr\u00eamio Fifa The Best, o atacante Vini Jr. foi o \u00fanico jogador brasileiro a figurar na sele\u00e7\u00e3o de 2024 da Federa\u00e7\u00e3o Internacional de Hist\u00f3ria e Estat\u00edstica do Futebol (IFFHS). O brasileiro foi preterido no Bola de Ouro, quando viu o espanhol Rodri ficar com o pr\u00eamio, mas encerra o ano com os t\u00edtulos da Copa Intercontinental, da Supercopa da Espanha, do Campeonato Espanhol, da Liga dos Campe\u00f5es e da Supercopa da Uefa.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Multicampe\u00e3o no ano, o Real Madrid \u00e9 o time com mais representantes na sele\u00e7\u00e3o da IFFHS, com 5 atletas, seguido por Manchester City, tetracampe\u00e3o do Ingl\u00eas, com 3. Aston Villa, Bayern de Munique e Barcelona contam um jogador cada um.<\/p>\n<p>A IFFHS montou um time no esquema 4-3-3. O goleiro do time \u00e9 o argentino<\/p>\n<p>Emiliano Martinez (Aston Villa). A defesa \u00e9 formada pelo espanhol Dani Carvajal Real Madrid, o portugu\u00eas Ruben Dias (Manchester City), o alem\u00e3o Antonio Rudiger (Real Madrid) e o canadense Alphonso Davies (Bayern de Munique).<\/p>\n<p>No meio-campo, aparecem Rodri (Manchester City), o ingl\u00eas Jude Bellingham (Real Madrid) e alem\u00e3o Toni Kroos (Real Madrid), que se aposentou ap\u00f3s a Euro. O trio de ataque conta com adolescente espanhol Lamine Yamal (Barcelona), o noruegu\u00eas Erling Haaland (Manchester City) e Vini Jr (Real Madrid).<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0 sele\u00e7\u00e3o da Fifa, h\u00e1 apenas uma mudan\u00e7a. Davies entra no lugar do franc\u00eas Wlliam Saliba, do Arsenal, na lateral-esquerda.<\/p>\n<p>Fonte: noticiasaominuto.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vencedor do pr\u00eamio Fifa The Best, o atacante Vini Jr. foi o \u00fanico jogador brasileiro<\/p>\n","protected":false},"author":0,"featured_media":40450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40449"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40449"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/40450"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}