{"id":40439,"date":"2024-12-27T14:45:08","date_gmt":"2024-12-27T17:45:08","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/27\/atriz-de-bridgerton-revela-que-a-mae-nao-gostou-das-suas-cenas-quentes\/"},"modified":"2024-12-27T14:45:08","modified_gmt":"2024-12-27T17:45:08","slug":"atriz-de-bridgerton-revela-que-a-mae-nao-gostou-das-suas-cenas-quentes","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/27\/atriz-de-bridgerton-revela-que-a-mae-nao-gostou-das-suas-cenas-quentes\/","title":{"rendered":"Atriz de Bridgerton revela que a m\u00e3e n\u00e3o gostou das suas cenas &#8216;quentes&#8217;"},"content":{"rendered":"<p>O trabalho de Nicola Coughlan n\u00e3o agradou a todos&#8230;nem \u00e0 pr\u00f3pria m\u00e3e!\u00a0<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Segundo a entrevista que a atriz deu ao programa de televis\u00e3o do apresentador Graham Norton, a sua m\u00e3e ficou chateada devido \u00e0s cenas mais quentes que ela protagonizou em &#8216;Bridgerton&#8217;.\u00a0<\/p>\n<p>&#8220;A minha m\u00e3e ficou com raiva de mim por causa daquelas cenas &#8211; como se a culpa fosse minha. Eu nem fui \u00e0 sess\u00e3o de estreia com ela!&#8221;<\/p>\n<p>&#8220;Eu tinha 35 anos e percebi que nunca tinha interpretado uma adulta [&#8230;] Foi t\u00e3o estranho interpretar uma protagonista rom\u00e2ntica e com cenas sexy&#8221;, disse a atriz que interpreta a personagem Penelope Featherington na s\u00e9rie.<\/p>\n<p>Nicola revelou ainda que insistiu com os produtores da s\u00e9rie para ter cenas de nudez, que no fim de tudo, considerou &#8220;empoderadoras&#8221;. &#8220;Eu senti que seria o maior &#8216;v\u00e1-se f****&#8217; para todas as conversas sobre o meu corpo.&#8221;\u00a0<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2243339\/sete-anos-depois-da-tragedia-em-manchester-ariana-grande-faz-doacao\" target=\"_blank\" rel=\"noopener\">Sete anos depois da trag\u00e9dia em Manchester, Ariana Grande faz doa\u00e7\u00e3o<\/a><\/p>\n<p>Fonte: noticiasaominuto.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O trabalho de Nicola Coughlan n\u00e3o agradou a todos&#8230;nem \u00e0 pr\u00f3pria m\u00e3e!\u00a0 \u00a0 Segundo a<\/p>\n","protected":false},"author":0,"featured_media":40440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40439"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40439"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/40440"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}