{"id":40435,"date":"2024-12-27T13:43:05","date_gmt":"2024-12-27T16:43:05","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/27\/idolos-da-selecao-aprovam-nome-de-ronaldo-para-a-cbf\/"},"modified":"2024-12-27T13:43:05","modified_gmt":"2024-12-27T16:43:05","slug":"idolos-da-selecao-aprovam-nome-de-ronaldo-para-a-cbf","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/27\/idolos-da-selecao-aprovam-nome-de-ronaldo-para-a-cbf\/","title":{"rendered":"\u00cddolos da sele\u00e7\u00e3o aprovam nome de Ronaldo para a CBF"},"content":{"rendered":"<p>RIO DE JANEIRO, RJ (UOL\/FOLHAPRESS) &#8211; Ronaldo Fen\u00f4meno quer ser presidente da CBF. O ex-jogador trabalha para concorrer na elei\u00e7\u00e3o do pr\u00f3ximo ano, j\u00e1 que o mandato de Ednaldo Rodrigues termina em 2026. Nomes importantes do futebol e da sele\u00e7\u00e3o brasileira manifestaram apoio a ele, que teve experi\u00eancia como gestor no Cruzeiro e no Valladolid.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>&#8220;Nas pr\u00f3ximas elei\u00e7\u00f5es serei candidato. Vou falar sobre futebol e mostrar meus projetos e planos. Quero fazer com que a gente resgate o prest\u00edgio no futebol brasileiro. Vou expor a necessidade de mudan\u00e7a e convencer os dirigentes de que meu projeto \u00e9 s\u00e9rio. Quero deixar um legado tamb\u00e9m como dirigente&#8221;, disse Ronaldo ao Jornal Nacional.O QUE DIZEM OS AMIGOS<br \/>Rom\u00e1rio revelou o desejo no passado de assumir a CBF e apoiou Ronaldo. Ele fez uma pondera\u00e7\u00e3o sobre a mudan\u00e7a dentro da entidade, mas acredita que o Fen\u00f4meno pode ajudar.<br \/>&#8220;Ronaldo j\u00e1 teve experi\u00eancia no futebol no Cruzeiro e no Valladolid. Ele foi bastante feliz, mostrou capacidade e compet\u00eancia. Tem no entorno pessoas para ajudar. Ser presidente da CBF n\u00e3o \u00e9 f\u00e1cil. Tamb\u00e9m j\u00e1 quis ser e vi a dificuldade que era. A CBF tem seus problemas. Deu uma mudada em rela\u00e7\u00e3o \u00e0 corrup\u00e7\u00e3o que era antes com Ricardo Teixeira, Jos\u00e9 Maria Marin e Del Nero. O presidente teve alguns erros, mas n\u00e3o vejo mais aquela escrotid\u00e3o de corrup\u00e7\u00e3o nesse atual mandato do Ednaldo. Mas quando falamos de Ronaldo podendo ser presidente da CBF, \u00e9 sempre interessante&#8221;, disse Rom\u00e1rio.ZINHO TAMB\u00c9M ACREDITA QUE RONALDO TENHA O QUE \u00c9 PRECISO<br \/>&#8220;Dif\u00edcil falar de um amigo, mas olhando pelo lado empresarial e profissional, o Ronaldo se preparou para isso. Tempos que ele j\u00e1 est\u00e1 nesse mercado como gestor, presidente. H\u00e1 pouco tempo era do Cruzeiro. \u00c9 muito pela presen\u00e7a dele que h\u00e1 o renascimento do clube. A grandeza, a camisa e a torcida o Cruzeiro tem de sobra, mas estava afundado em um mar de d\u00edvidas e problemas grav\u00edssimos, na segunda divis\u00e3o. O Ronaldo foi importante para a volta \u00e0 primeira divis\u00e3o. Acho que ele est\u00e1 capacitado para isso. E vem tamb\u00e9m o nome do fen\u00f4meno, as portas que se abrem para a CBF. O Brasil vai chegar com o representante, que \u00e9 o Ronaldo. A Fifa olha diferente, a Conmebol, o mundo. Vai depender, se ele for mesmo, o que vai fazer para potencializar isso&#8221;, disse Zinho.<br \/>Ronaldo Fen\u00f4meno j\u00e1 manifestou esse desejo muitos anos antes. Em 2022, ap\u00f3s elimina\u00e7\u00e3o na Copa no Qatar, disse em entrevista coletiva que estava \u00e0 disposi\u00e7\u00e3o da confedera\u00e7\u00e3o brasileira para &#8220;ajudar no que fosse preciso&#8221;.<\/p>\n<p>Fonte: noticiasaominuto.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RIO DE JANEIRO, RJ (UOL\/FOLHAPRESS) &#8211; Ronaldo Fen\u00f4meno quer ser presidente da CBF. O ex-jogador<\/p>\n","protected":false},"author":0,"featured_media":40436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40435"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40435"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/40436"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}