{"id":39876,"date":"2024-12-21T14:00:27","date_gmt":"2024-12-21T17:00:27","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/21\/policia-civil-cumpre-mandado-contra-jovem-foragida-e-apreende-80-porcoes-de-droga\/"},"modified":"2024-12-21T14:00:27","modified_gmt":"2024-12-21T17:00:27","slug":"policia-civil-cumpre-mandado-contra-jovem-foragida-e-apreende-80-porcoes-de-droga","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/12\/21\/policia-civil-cumpre-mandado-contra-jovem-foragida-e-apreende-80-porcoes-de-droga\/","title":{"rendered":"Pol\u00edcia Civil cumpre mandado contra jovem foragida e apreende 80 por\u00e7\u00f5es de droga"},"content":{"rendered":"<div>\n<div id=\"infocoweb\" data-uuid=\"24772433-aa21-4e07-bc1c-069163fcfb8d\" class=\"infocoweb infocoweb_canal_42\">\n<div id=\"infocoweb_cabecalho\" class=\"infocoweb_cabecalho\"><\/div>\n<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\"><span class=\"ifn_post_add_feature_image_to_the_top\"><\/span><\/p>\n<p style=\"text-align: justify\">Uma jovem foragida da Justi\u00e7a foi presa pela Pol\u00edcia Civil, nesta quinta-feira (19.12), no munic\u00edpio de Campos de J\u00falio. Com ela, foram apreendidas cerca de 80 por\u00e7\u00f5es de entorpecentes, tr\u00eas carregadores de arma de fogo, balan\u00e7a de precis\u00e3o e entre outros materiais. Por isso, ela tamb\u00e9m foi autuada em flagrante por tr\u00e1fico de drogas, resist\u00eancia, desobedi\u00eancia e les\u00e3o corporal.<\/p>\n<p style=\"text-align: justify\">A procurada, de 21 anos, estava com o mandado de pris\u00e3o decretado pelos crimes de roubo, extors\u00e3o e tortura cometidos pela comarca de Sapezal.<\/p>\n<p style=\"text-align: justify\">Os policiais civis da Delegacia de Sapezal realizaram dilig\u00eancias para localizar a foragida e identificaram que a mesma estava escondida em uma resid\u00eancia na cidade de Campos de J\u00falio.<\/p>\n<p style=\"text-align: justify\">Com base nas informa\u00e7\u00f5es, a equipe deslocou at\u00e9 Campos de J\u00falio e, com apoio do investigador da cidade, passaram a monitorar o endere\u00e7o levantado. Ap\u00f3s certo tempo de campana, os policiais civis avistaram a jovem saindo do im\u00f3vel.<\/p>\n<p style=\"text-align: justify\">Ao ser abordada, a suspeita tentou correr para dentro da quitinete. Ela resistiu a a\u00e7\u00e3o e agiu com viol\u00eancia, desferindo v\u00e1rios golpes e causando les\u00f5es na equipe.<\/p>\n<p style=\"text-align: justify\">Durante busca pessoal realizada por uma investigadora, foi encontrado embaixo das roupas da suspeita duas meias com 30 por\u00e7\u00f5es de pasta base de coca\u00edna e um aparelho celular.<\/p>\n<p style=\"text-align: justify\">No interior do im\u00f3vel, tamb\u00e9m foram localizadas mais 50 por\u00e7\u00f5es de droga, um notebook, uma maleta da Taurus contendo tr\u00eas carregadores de pistola calibre 9 mil\u00edmetros e uma balan\u00e7a de precis\u00e3o.<\/p>\n<p style=\"text-align: justify\">Diante dos fatos e da ordem judicial de pris\u00e3o em aberto, a jovem foi conduzida at\u00e9 a Delegacia de Campos de J\u00falio, onde foi interrogada, autuada em flagrante e dado cumprimento ao mandado judicial.<\/p>\n<p style=\"text-align: justify\">Ap\u00f3s a confec\u00e7\u00e3o dos autos, a presa foi colocada \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte: Policia Civil MT \u2013 MT<\/p>\n<style>#infocoweb_cabecalho {\n        display: inline-block;\n        margin-top: -75px;\n        position: absolute;\n        right: 0;\n    }\n<\/style>\n<style><\/style>\n<\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\"><\/div>\n<\/div>\n<p>O post Pol\u00edcia Civil cumpre mandado contra jovem foragida e apreende 80 por\u00e7\u00f5es de droga apareceu primeiro em Portal MT.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma jovem foragida da Justi\u00e7a foi presa pela Pol\u00edcia Civil, nesta quinta-feira (19.12), no munic\u00edpio<\/p>\n","protected":false},"author":2,"featured_media":39877,"comment_status":"registered_only","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39876"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39876"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/39877"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}