{"id":35131,"date":"2024-11-16T13:43:33","date_gmt":"2024-11-16T16:43:33","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/11\/16\/flamengo-vive-lacunas-com-adeus-do-idolo-e-lesao-de-pedro\/"},"modified":"2024-11-16T13:43:33","modified_gmt":"2024-11-16T16:43:33","slug":"flamengo-vive-lacunas-com-adeus-do-idolo-e-lesao-de-pedro","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/11\/16\/flamengo-vive-lacunas-com-adeus-do-idolo-e-lesao-de-pedro\/","title":{"rendered":"Flamengo vive lacunas com adeus do \u00eddolo e les\u00e3o de Pedro"},"content":{"rendered":"<p>BRUNO BRAZ<br \/>RIO DE JANEIRO, RJ (UOL\/FOLHAPRESS) &#8211; Com o adeus consumado segundo as palavras do pr\u00f3prio Gabigol, o Flamengo vive um desafio para 2025: preencher as lacunas no ataque deixadas n\u00e3o s\u00f3 por ele como tamb\u00e9m por Pedro, artilheiro da equipe na temporada e que, por causa da grave les\u00e3o, s\u00f3 ir\u00e1 retornar aos gramados no meio do ano que vem.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p><span class=\"news_bold\">O QUE ACONTECEU<\/span><br \/>A tend\u00eancia \u00e9 a de que o Flamengo v\u00e1 ao mercado em busca de um centroavante. Pelo menos \u00e9 o que garante o atual presidente do clube, Rodolfo Landim, apesar de terem elei\u00e7\u00f5es marcadas para dezembro e n\u00e3o haver certeza de que o seu candidato de situa\u00e7\u00e3o, Rodrigo Dunshee, ir\u00e1 vencer o pleito.<\/p>\n<p>Vice de futebol atual, Marcos Braz deixou claro que n\u00e3o continua em 2025 independente de quem ven\u00e7a. Foi o dirigente, ao lado do diretor-executivo Bruno Spindel, que tomou frente de todas as negocia\u00e7\u00f5es de jogadores de 2019 para c\u00e1.<\/p>\n<p>Certamente vamos procurar jogador para essa posi\u00e7\u00e3o, mas para isso, no nosso or\u00e7amento, estamos deixando um volume de recursos previstos.Rodolfo Landim, ao podcast &#8220;Flow&#8221;<\/p>\n<p>Para a reta final do Campeonato Brasileiro, Filipe Luis utilizar\u00e1 o que tem \u00e0 disposi\u00e7\u00e3o. Atualmente, o treinador tem utilizado Bruno Henrique no setor. Outra op\u00e7\u00e3o \u00e9 Carlinhos, que tem caracter\u00edsticas mais fixas, de \u00e1rea, por\u00e9m o ex-Nova Igua\u00e7u encontra-se lesionado.<\/p>\n<p>Filipe Luis tamb\u00e9m j\u00e1 destacou que v\u00ea Plata atuando na fun\u00e7\u00e3o. O t\u00e9cnico enxerga o equatoriano como um atacante que pode ser utilizado tanto como centroavante como ponta.<\/p>\n<p><span class=\"news_bold\">GABIGOL AFASTADO PELA DIRETORIA<\/span><br \/>Gabigol foi afastado pela diretoria mesmo com os desfalques no setor. Em conversas avan\u00e7adas com o Cruzeiro, ele n\u00e3o foi relacionado para o jogo contra o Atl\u00e9tico-MG, na \u00faltima quarta-feira (13), e acompanhou a partida de um dos camarotes do Maracan\u00e3.<\/p>\n<p>O motivo ainda gera pol\u00eamica: a diretoria justifica por supostos atos de indisciplina do atacante, algo que o jogador e seus estafe negam.<br \/>Ap\u00f3s o jogo, Filipe Luis deu um breve pronunciamento. O treinador deixou claro que a decis\u00e3o partiu da diretoria:<\/p>\n<p>&#8220;Primeiro, dizer que me entristece profundamente falar de um assunto desse depois de ser campe\u00e3o. Sou grato \u00e0 diretoria por ter confiado em mim em 2019, por ter me colocado aqui. Sou grato ao Gabriel, por tudo que ele fez pelo clube e por mim. Sobre o afastamento, devido a um epis\u00f3dio que aconteceu na final, fui comunicado pelo Marcos Braz de que ele n\u00e3o seria relacionado at\u00e9 segunda ordem. Esse \u00e9 um assunto total do Marcos Braz e ele vai falar no momento que achar oportuno. Esse \u00e9 meu pronunciamento, que me entristece profundamente. N\u00e3o gostaria que esse assunto sujasse esse t\u00edtulo que o grupo conquistou por um motivo extracampo&#8221;, disse Filipe Luis<\/p>\n<p>Fonte: noticiasaominuto.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BRUNO BRAZRIO DE JANEIRO, RJ (UOL\/FOLHAPRESS) &#8211; Com o adeus consumado segundo as palavras do<\/p>\n","protected":false},"author":0,"featured_media":35132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35131"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=35131"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/35132"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=35131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=35131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=35131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}