{"id":17001,"date":"2024-07-07T11:43:19","date_gmt":"2024-07-07T14:43:19","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/07\/07\/endrick-lamenta-queda-na-copa-america-e-ja-vislumbra-futuro-cabeca-em-madri\/"},"modified":"2024-07-07T11:43:19","modified_gmt":"2024-07-07T14:43:19","slug":"endrick-lamenta-queda-na-copa-america-e-ja-vislumbra-futuro-cabeca-em-madri","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/07\/07\/endrick-lamenta-queda-na-copa-america-e-ja-vislumbra-futuro-cabeca-em-madri\/","title":{"rendered":"Endrick lamenta queda na Copa Am\u00e9rica e j\u00e1 vislumbra futuro: &#8216;Cabe\u00e7a em Madri&#8217;"},"content":{"rendered":"<p>Titular na partida em que a sele\u00e7\u00e3o brasileira foi eliminada pelo Uruguai nas quartas de final da Copa Am\u00e9rica ap\u00f3s disputa de p\u00eanaltis, o centroavante Endrick comentou sobre o seu futuro.<\/p>\n<p>Negociado pelo Palmeiras com o Real Madrid, o jogador de 17 anos deu r\u00e1pida entrevista durante passagem pela zona mista. Abatido pelo rev\u00e9s, admitiu j\u00e1 estar pensando em sua nova fase na carreira.<\/p>\n<\/p>\n<p>&#8220;Agora sim eu penso em Madri. \u00c9 muito dif\u00edcil falar porque infelizmente aconteceu uma coisa horr\u00edvel de a gente ser eliminado (da Copa Am\u00e9rica), mas \u00f3bvio que agora a minha cabe\u00e7a est\u00e1 em Madri&#8221;, afirmou o jogador em v\u00eddeo veiculado pelo jornal espanhol Marca.<\/p>\n<\/p>\n<p>Na conversa, ele comentou sobre o confronto com o uruguaio Valverde, que ser\u00e1 seu companheiro de clube na equipe merengue. &#8220;\u00c9 um grande jogador, um jogador, um cara que se doa muito para o time, se doa muito para a sele\u00e7\u00e3o&#8221;, afirmou.<\/p>\n<\/p>\n<p>Por fim, o camisa nove mandou um recado para torcida brasileira e pediu apoio aos jogadores ap\u00f3s a sa\u00edda precoce da Copa Am\u00e9rica. &#8220;Sei que \u00e9 dif\u00edcil aceitar a elimina\u00e7\u00e3o do nosso pa\u00eds nas quartas de final, mas espero que as pessoas estejam conosco no futuro&#8221;.<\/p>\n<p>Fonte: noticiasaominuto.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Titular na partida em que a sele\u00e7\u00e3o brasileira foi eliminada pelo Uruguai nas quartas de<\/p>\n","protected":false},"author":0,"featured_media":17002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17001"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17001"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/17002"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}