{"id":14428,"date":"2024-06-21T17:43:18","date_gmt":"2024-06-21T20:43:18","guid":{"rendered":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/06\/21\/errado-e-trair-e-ter-varias-amantes-diz-tadeu-schmidt-sobre-filha-queer\/"},"modified":"2024-06-21T17:43:18","modified_gmt":"2024-06-21T20:43:18","slug":"errado-e-trair-e-ter-varias-amantes-diz-tadeu-schmidt-sobre-filha-queer","status":"publish","type":"post","link":"https:\/\/portalnewsgta.com.br\/index.php\/2024\/06\/21\/errado-e-trair-e-ter-varias-amantes-diz-tadeu-schmidt-sobre-filha-queer\/","title":{"rendered":"Errado \u00e9 trair e ter v\u00e1rias amantes, diz Tadeu Schmidt sobre filha queer"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Tadeu Schmidt se prepara para o in\u00edcio das Olimp\u00edadas de Paris. O apresentador vai comandar, ao lado de Fernanda Garay, a Central Ol\u00edmpica, que vai resumir o dia nos Jogos Ol\u00edmpicos de Paris em hor\u00e1rio nobre na emissora.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>No m\u00eas do orgulho LGBTQIA+, o tamb\u00e9m apresentador do BBB deixou claro o orgulho que sente da filha mais velha, Valentina. A jovem se define como uma pessoa queer.<\/p>\n<p>&#8220;Errado \u00e9 trair, \u00e9 voc\u00ea ser um casal h\u00e9tero e ter v\u00e1rias amantes. Errado \u00e9 ser desonesto, ser mentiroso&#8221;, disse. Para ele, o caminho para o fim da homofobia \u00e9 uma via de m\u00e3o \u00fanica que n\u00e3o tem volta.<\/p>\n<p>O jornalista relembrou falas homof\u00f3bicas que teve ao longo da vida, inclusive com colegas de profiss\u00e3o. Em uma das ocasi\u00f5es, foi corrigido por Murilo Salviano, correspondente da Globo em Londres.<\/p>\n<p>&#8220;Um colega me alertou que algu\u00e9m tinha se assumido gay, e eu disse &#8216;caramba, pensei que ele era homem&#8217;. Ele falou &#8216;Tadeu, homem ele \u00e9, ele n\u00e3o \u00e9 h\u00e9tero, ele \u00e9 homossexual'&#8221;, afirmou em entrevista \u00e0 revista Quem.<\/p>\n<p>At\u00e9 hoje, ele diz cometer deslizes, mas conta com a ajuda da esposa, Ana Cristina, e tamb\u00e9m da filha mais nova, Laura.<\/p>\n<p>&#8220;Se vejo um stand-up e tem uma piada falando de homem e mulher, eu mando no grupo da fam\u00edlia &#8216;voc\u00eas acham que \u00e9 machismo?&#8217;, e elas falam &#8216;\u00e9 machismo&#8217;. Aprendo com elas que n\u00e3o \u00e9 s\u00f3 uma brincadeira. \u00c9 um processo eterno, e eu nunca vou ser \u00e0 prova de falhas.&#8221;<\/p>\n<p>Fonte: noticiasaominuto.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Tadeu Schmidt se prepara para o in\u00edcio das Olimp\u00edadas de<\/p>\n","protected":false},"author":0,"featured_media":14429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14428"}],"collection":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14428"}],"version-history":[{"count":0,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media\/14429"}],"wp:attachment":[{"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnewsgta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}